{"id":1995,"date":"2015-12-12T19:39:52","date_gmt":"2015-12-12T18:39:52","guid":{"rendered":"https:\/\/www.ionas.com\/wissen\/?p=1995"},"modified":"2016-09-10T07:16:14","modified_gmt":"2016-09-10T06:16:14","slug":"vorsorge-fuer-den-komplettausfall-systemabbildsicherung","status":"publish","type":"post","link":"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/","title":{"rendered":"Vorsorge f\u00fcr den Komplettausfall: Systemabbildsicherung"},"content":{"rendered":"<p>Ein Systemabbild &#8211; oder neudeutsch Systemimage &#8211; ist \u201eeine Kopie der f\u00fcr die Ausf\u00fchrung von Windows erforderlichen Laufwerke.\u201c Der Haupteinsatzweck eines solchen Images: \u201eEin Systemimage kann verwendet werden, um den Computer im Falle eines Computer- oder Festplattendefekts wiederherzustellen.\u201c<\/p>\n<p>Diese Definitionen stammen aus der Systemabbildsicherung von Windows. Mit diesem Systemtool lassen sich bequem Images der Systemdatentr\u00e4ger anfertigen. In diesem Artikel erl\u00e4utern wir, wie genau das funktioniert und wie man Systemabbilder verwenden kann, um ein System im Schadenfall schnellstm\u00f6glich wieder flott zu machen.<\/p>\n<p><!--more--><\/p>\n<h2>Erstellung eines Systemabbildes<\/h2>\n<p><img loading=\"lazy\" src=\"https:\/\/www.ionas.com\/wissen\/wp-content\/uploads\/2015\/12\/Systemabbildung-Dateiversionsverlauf.png\" alt=\"Systemabbildsicherung im Dateiversionsverlauf-Fenster\" width=\"485\" height=\"304\" class=\"alignnone size-full wp-image-2005\" style=\"float:left; padding: 10px 20px 0px 0px;\"\/> Die \u00dcberschrift Datensicherung vereint thematisch die Systemabbildsicherung und den Windows-Dateiversionsverlauf. Auch wenn diese beiden Windows-Systemprogramme sonst nicht viel miteinander zu tun haben, so scheint diese thematische Zusammengeh\u00f6rigkeit den Microsoft-Entwicklern auszureichen, um die Einrichtung der Abbildsicherung dem Versionsverlauf zuzuordnen. Anders ist es nicht zu erkl\u00e4ren, dass man den Dialog zur Erstellung eines Systemabbilds nur \u00fcber das Fenster des Dateiversionsverlaufs erreichen kann. Am unteren Rand der linken Navigationsleiste findet man die &#8216;Systemabbildsicherung&#8217;.<\/p>\n<p><img loading=\"lazy\" src=\"https:\/\/www.ionas.com\/wissen\/wp-content\/uploads\/2015\/12\/Systemabbildsicherung_Screenshot.png\" alt=\"Systemabbildsicherung Screenshot\" width=\"482\" height=\"448\" class=\"alignnone size-full wp-image-1983\" style=\"float:right; padding: 0px 0px 0px 20px;\" srcset=\"https:\/\/www.ionas.com\/wissen\/wp-content\/uploads\/2015\/12\/Systemabbildsicherung_Screenshot.png 642w, https:\/\/www.ionas.com\/wissen\/wp-content\/uploads\/2015\/12\/Systemabbildsicherung_Screenshot-300x279.png 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/> Hat man diese H\u00fcrde erst einmal \u00fcberwunden und ist im &#8216;Systemimage erstellen&#8217;-Dialog angekommen (siehe Abbildung), dann ist das Image selbst nicht mehr weit. Man w\u00e4hlt das Ziel-Sicherungsmedium und kann dann per Klick auf den ungl\u00fccklich benannten Button \u201eSicherung starten\u201c die Erstellung des Systemabbilds beginnen. Eine andere Beschriftung w\u00e4re passender, handelt es sich doch bei einem Systemabbild nicht um eine Datensicherung im engeren Sinn.<\/p>\n<p>Das Systemabbild kann auf alle angeschlossenen Festplatten, USB-Sticks und Netzlaufwerke erfolgen. Interessant ist, dass die Systemabbildsicherung das Systemimage auch auf einer Partition des Systemdatentr\u00e4gers abgelegen kann. Beim <a href=>Dateiversionsverlauf<\/a> wird dies programmseitig aus gutem Grund ausgeschlossen. Das Speichermedium, das als Sicherungsdatentr\u00e4ger dienen soll, sollte ann\u00e4hernd so gro\u00df sein wie der belegte Speicher auf dem Systemlaufwerk. Das Image packt zwar die Dateien, eine hohe Kompressionsrate sollte man aber nicht erwarten. Theoretisch erlaubt der Einrichtungsdialog auch die Ablage des Images auf einer oder mehreren DVDs. Jedoch ist nicht alles, was m\u00f6glich ist, auch sinnvoll. Angesichts g\u00e4ngiger Festplattengr\u00f6\u00dfen im TB-Bereich kann man sich leicht den Stapel an DVDs ausmalen, der f\u00fcr ein Image notwendig w\u00e4re. Diese Option sollte daher nur dann gew\u00e4hlt werden, wenn alle andere M\u00f6glichkeiten aus gutem Grund ausgeschlossen sind.<\/p>\n<p>Die Dauer der Abbilderstellung durch die Systemabbildsicherung im Virtuell-Hard-Disk Format, kurz VHDX, schwankt zwischen wenigen Minuten und einigen Stunden. Als komplette 1:1-Kopie des gesamten Systemlaufwerks dauert die Erstellung bei einem vollen Systemdatentr\u00e4ger l\u00e4nger als bei einer leeren. Aus diesem Grund macht es auch Sinn, vor der Erstellung die Dienste der Datentr\u00e4gerbereinigung zu bem\u00fchen. Ansonsten packt man unn\u00f6tigen Ballast in das Image. Eine langsame Quellfestplatte genauso wie ein gem\u00e4chliches Ziel-Sicherungslaufwerk sind ebenfalls entscheidend f\u00fcr die Geschwindigkeit.<\/p>\n<p>Schaut man auf dem Ziellaufwerk nach, findet man dort nach Abschluss einen Ordner mit dem Namen WindowsImageBackup. In diesem findet man wiederrum die Datei Mediald und diese vier Ordner:<\/p>\n<ul>\n<li>Backup [Datum] [Uhrzeit]<\/li>\n<li>Catalog<\/li>\n<li>Logs<\/li>\n<li>SPPMetadataCache<\/li>\n<\/ul>\n<p>Das eigentliche Systemimage liegt im Ordner Backup.<\/p>\n\n<h2>Wiederherstellung eines Systemabbilds<\/h2>\n<p>Das erstellte Systemabbild l\u00e4sst sich \u00fcber die Windows-Wiederherstellungsumgebung (englisch: Windows Recovery Environment bzw. Windows RE) einspielen. Der Weg dorthin ist leider bei Windows 8 und Windows 10 ein wenig umst\u00e4ndlich &#8211; auch wenn das System noch normal startet.<\/p>\n<p>Bei einem noch <u>normal startenden Betriebssystem<\/u> ist der einfachste Weg in die Windows Recovery Environment \u00fcber die erweiterten <a href=\"http:\/\/windows.microsoft.com\/de-de\/windows-8\/windows-startup-settings-safe-mode\">Startoptionen<\/a>. Aufgrund der unterschiedlichen Oberfl\u00e4chen &#8211; Windows 8 mit Modern UI und ohne Start-Button, Windows 10 ohne Modern UI und mit Start-Button &#8211; unterscheiden sich aber die Einstiegspunkte. In Windows 8 geht der Weg \u00fcber &#8216;PC-Einstellungen \u00e4ndern&#8217; im Charms-Bar. In Windows 10 klickt man auf den Start-Button und w\u00e4hlt dann &#8216;Einstellungen&#8217; an. Der weitere Pfad ist f\u00fcr beide Betriebssysteme gleich: Im Submen\u00fc &#8216;Update\/Wiederherstellung&#8217; findet man unter dem Navigationspunkt &#8216;Wiederherstellung&#8217; die M\u00f6glichkeit, den erweiterten Start aufzurufen. Mit Klick darauf startet der Computer neu und bootet automatisch in die Wiederherstellungsumgebung.<\/p>\n<p><u>Startet der Computer nicht mehr richtig<\/u>, dann versucht Windows nach wiederholtem Fehlstart automatisch in die Wiederherstellungsumgebung zu wechseln. Wenn dies nicht automatisch passiert, dann l\u00e4sst sich das auch provozieren. Man muss den Computer einfach mehrmals w\u00e4hrend des Startprozesses (d.h. nach Anzeige des Herstellerlogos) \u00fcber den Power-Knopf ausgeschalten Sp\u00e4testens nach dem dritten Mal startet der Rechner in die Wiederherstellungsumgebung.<\/p>\n<p><img loading=\"lazy\" src=\"https:\/\/www.ionas.com\/wissen\/wp-content\/uploads\/2015\/12\/Wiederherstellung-Dialog.png\" alt=\"Wiederherstellung Dialog\" width=\"550\" height=\"283\" class=\"alignnone size-full wp-image-2014\" style=\"float:right; padding: 0px 0px 0px 20px;\" srcset=\"https:\/\/www.ionas.com\/wissen\/wp-content\/uploads\/2015\/12\/Wiederherstellung-Dialog-300x155.png 300w, https:\/\/www.ionas.com\/wissen\/wp-content\/uploads\/2015\/12\/Wiederherstellung-Dialog-768x397.png 768w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/> <u>Bei einem gar nicht mehr startenden Computer<\/u> &#8211; weil die Hardware Schaden genommen hat oder der ganze Rechner abhandengekommen ist &#8211; ben\u00f6tigt man ein Windows 8 oder Windows 10 Installationsmedium, um das Systemabbild auf einem neuen Rechner bzw. einer neuen Festplatte aufzuspielen. Fr\u00fcher lag ein solches Medium h\u00e4ufig in Form einer CD bzw. DVD bei. In Zeiten aussterbender optischer Datentr\u00e4ger ist dies nicht mehr der Fall. Ein un\u00fcberwindliches Problem ist das nicht, aber es bedarf Vorkehrungen: \u00dcber den Wiederherstellung-Dialog in der Systemsteuerung lassen sich Wiederherstellungsmedien einfach erstellen (siehe Abbildung) &#8211; aber nur wenn der Computer noch bootet. Als Systemreparaturdatentr\u00e4ger bieten sich USB-Sticks an. Wenn ein solcher Rettungsdatentr\u00e4ger vorab nicht erstellt wurde, dann empfehlen wir Ihnen den <a href=\"\/rescue-stick\">ionas-Rescue Stick<\/a> &#8211; die smarte L\u00f6sung zum Pr\u00fcfen, Retten und Installieren aus dem Hause ionas.<\/p>\n<h2>Systemabbildsicherung = sicher; Systemabbildsicherung + Dateiversionsverlauf = sicherer<\/h2>\n<p>Sicherheitsbewusste Computernutzer sollten sich die Einfachheit der Systemabbildsicherung zu Eigen machen und in regelm\u00e4\u00dfigen Abst\u00e4nden Systemimages anfertigen. Im Schadenfall ist damit der Computer schnell wieder einsatzbereit und auch vor Datenverlust kann man sich mit ihm sch\u00fctzen. Ebenfalls gute Dienste leistet ein Systemabbild f\u00fcr den Fall, dass der Computer Auff\u00e4lligkeiten nach einem Windows Update oder einer Treiber Aktualisierung aufweist und die Fehlerbehebung \u00fcber einen <a href=\"\/wissen\/systemwiederherstellung-bei-windows-systemproblemen\/\">Wiederherstellungspunkt<\/a> scheitert. Das Wiedereinspielen des Images macht die System\u00e4nderungen wirksam r\u00fcckg\u00e4ngig.<\/p>\n<p>Optimal ist eine kombinierte Strategie, die die beiden Datensicherungs-Bordmittel von Windows sinnvoll miteinander kombiniert: Monatliche Systemimages mit der Systemabbildsicherung sollten durch t\u00e4gliche L\u00e4ufe des Dateiversionsverlaufs erg\u00e4nzt werden. So lassen sich die Wiederherstellungszeit des Systems und der vermutliche Datenverlust ohne gro\u00dfen Aufwand minimieren. Zu beachten gilt, dass die Sicherung auf jeden Fall auf einen separaten Datentr\u00e4ger erfolgen sollte. Eine externe Festplatte mittlerer Gr\u00f6\u00dfe ist nicht teuer und leistet daf\u00fcr gute Dienste.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Systemabbild &#8211; oder neudeutsch Systemimage &#8211; ist \u201eeine Kopie der f\u00fcr die Ausf\u00fchrung von Windows erforderlichen Laufwerke.\u201c Der Haupteinsatzweck eines solchen Images: \u201eEin Systemimage kann verwendet werden, um den Computer im Falle eines Computer- oder Festplattendefekts wiederherzustellen.\u201c Diese Definitionen stammen aus der Systemabbildsicherung von Windows. Mit diesem Systemtool lassen sich bequem Images der Systemdatentr\u00e4ger [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[211,216,215,217,28],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vorsorge f\u00fcr den Komplettausfall: Systemabbildsicherung | ionas<\/title>\n<meta name=\"description\" content=\"Die Systemabbildsicherung erstellt mit wenigen Klicks ein Systemimage. Nutzen Sie diesen Sicherheitsgewinn f\u00fcr sich! Lesen sie hier, wie es geht.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vorsorge f\u00fcr den Komplettausfall: Systemabbildsicherung | ionas\" \/>\n<meta property=\"og:description\" content=\"Die Systemabbildsicherung erstellt mit wenigen Klicks ein Systemimage. Nutzen Sie diesen Sicherheitsgewinn f\u00fcr sich! Lesen sie hier, wie es geht.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/\" \/>\n<meta property=\"og:site_name\" content=\"ionas Wissen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IhrOnlineAssistent\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-12T18:39:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-09-10T06:16:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ionas.com\/wissen\/wp-content\/uploads\/2015\/12\/Systemabbildung-Dateiversionsverlauf.png\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ralf Dyllick-Brenzinger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ionas.com\/wissen\/#organization\",\"name\":\"ionas OHG\",\"url\":\"https:\/\/www.ionas.com\/wissen\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/IhrOnlineAssistent\",\"https:\/\/twitter.com\/ionasohg\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.ionas.com\/wissen\/#logo\",\"inLanguage\":\"de-DE\",\"url\":\"https:\/\/www.ionas.com\/wissen\/wp-content\/uploads\/2014\/12\/ionas-logo.jpg\",\"contentUrl\":\"https:\/\/www.ionas.com\/wissen\/wp-content\/uploads\/2014\/12\/ionas-logo.jpg\",\"width\":150,\"height\":68,\"caption\":\"ionas OHG\"},\"image\":{\"@id\":\"https:\/\/www.ionas.com\/wissen\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ionas.com\/wissen\/#website\",\"url\":\"https:\/\/www.ionas.com\/wissen\/\",\"name\":\"ionas Wissen\",\"description\":\"Artikel, Videos, Anleitungen, Tipps ...\",\"publisher\":{\"@id\":\"https:\/\/www.ionas.com\/wissen\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ionas.com\/wissen\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/#primaryimage\",\"inLanguage\":\"de-DE\",\"url\":\"https:\/\/www.ionas.com\/wissen\/wp-content\/uploads\/2015\/12\/Systemabbildung-Dateiversionsverlauf.png\",\"contentUrl\":\"https:\/\/www.ionas.com\/wissen\/wp-content\/uploads\/2015\/12\/Systemabbildung-Dateiversionsverlauf.png\",\"width\":870,\"height\":609,\"caption\":\"Systemabbildsicherung im Dateiversionsverlauf-Fenster\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/#webpage\",\"url\":\"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/\",\"name\":\"Vorsorge f\u00fcr den Komplettausfall: Systemabbildsicherung | ionas\",\"isPartOf\":{\"@id\":\"https:\/\/www.ionas.com\/wissen\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/#primaryimage\"},\"datePublished\":\"2015-12-12T18:39:52+00:00\",\"dateModified\":\"2016-09-10T06:16:14+00:00\",\"description\":\"Die Systemabbildsicherung erstellt mit wenigen Klicks ein Systemimage. Nutzen Sie diesen Sicherheitsgewinn f\u00fcr sich! Lesen sie hier, wie es geht.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ionas.com\/wissen\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vorsorge f\u00fcr den Komplettausfall: Systemabbildsicherung\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.ionas.com\/wissen\/#\/schema\/person\/4f6d598597b4cb184645f0851f8bdea7\"},\"headline\":\"Vorsorge f\u00fcr den Komplettausfall: Systemabbildsicherung\",\"datePublished\":\"2015-12-12T18:39:52+00:00\",\"dateModified\":\"2016-09-10T06:16:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/#webpage\"},\"wordCount\":1009,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.ionas.com\/wissen\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ionas.com\/wissen\/wp-content\/uploads\/2015\/12\/Systemabbildung-Dateiversionsverlauf.png\",\"keywords\":[\"datensicherung\",\"image\",\"systemabbild\",\"systemimage\",\"Windows\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ionas.com\/wissen\/#\/schema\/person\/4f6d598597b4cb184645f0851f8bdea7\",\"name\":\"Ralf Dyllick-Brenzinger\",\"sameAs\":[\"http:\/\/www.ionas.com\"],\"url\":\"https:\/\/www.ionas.com\/wissen\/author\/rdb\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vorsorge f\u00fcr den Komplettausfall: Systemabbildsicherung | ionas","description":"Die Systemabbildsicherung erstellt mit wenigen Klicks ein Systemimage. Nutzen Sie diesen Sicherheitsgewinn f\u00fcr sich! Lesen sie hier, wie es geht.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/","og_locale":"de_DE","og_type":"article","og_title":"Vorsorge f\u00fcr den Komplettausfall: Systemabbildsicherung | ionas","og_description":"Die Systemabbildsicherung erstellt mit wenigen Klicks ein Systemimage. Nutzen Sie diesen Sicherheitsgewinn f\u00fcr sich! Lesen sie hier, wie es geht.","og_url":"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/","og_site_name":"ionas Wissen","article_publisher":"https:\/\/www.facebook.com\/IhrOnlineAssistent","article_published_time":"2015-12-12T18:39:52+00:00","article_modified_time":"2016-09-10T06:16:14+00:00","og_image":[{"url":"https:\/\/www.ionas.com\/wissen\/wp-content\/uploads\/2015\/12\/Systemabbildung-Dateiversionsverlauf.png"}],"twitter_misc":{"Verfasst von":"Ralf Dyllick-Brenzinger","Gesch\u00e4tzte Lesezeit":"5 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.ionas.com\/wissen\/#organization","name":"ionas OHG","url":"https:\/\/www.ionas.com\/wissen\/","sameAs":["https:\/\/www.facebook.com\/IhrOnlineAssistent","https:\/\/twitter.com\/ionasohg"],"logo":{"@type":"ImageObject","@id":"https:\/\/www.ionas.com\/wissen\/#logo","inLanguage":"de-DE","url":"https:\/\/www.ionas.com\/wissen\/wp-content\/uploads\/2014\/12\/ionas-logo.jpg","contentUrl":"https:\/\/www.ionas.com\/wissen\/wp-content\/uploads\/2014\/12\/ionas-logo.jpg","width":150,"height":68,"caption":"ionas OHG"},"image":{"@id":"https:\/\/www.ionas.com\/wissen\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.ionas.com\/wissen\/#website","url":"https:\/\/www.ionas.com\/wissen\/","name":"ionas Wissen","description":"Artikel, Videos, Anleitungen, Tipps ...","publisher":{"@id":"https:\/\/www.ionas.com\/wissen\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ionas.com\/wissen\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"ImageObject","@id":"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/#primaryimage","inLanguage":"de-DE","url":"https:\/\/www.ionas.com\/wissen\/wp-content\/uploads\/2015\/12\/Systemabbildung-Dateiversionsverlauf.png","contentUrl":"https:\/\/www.ionas.com\/wissen\/wp-content\/uploads\/2015\/12\/Systemabbildung-Dateiversionsverlauf.png","width":870,"height":609,"caption":"Systemabbildsicherung im Dateiversionsverlauf-Fenster"},{"@type":"WebPage","@id":"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/#webpage","url":"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/","name":"Vorsorge f\u00fcr den Komplettausfall: Systemabbildsicherung | ionas","isPartOf":{"@id":"https:\/\/www.ionas.com\/wissen\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/#primaryimage"},"datePublished":"2015-12-12T18:39:52+00:00","dateModified":"2016-09-10T06:16:14+00:00","description":"Die Systemabbildsicherung erstellt mit wenigen Klicks ein Systemimage. Nutzen Sie diesen Sicherheitsgewinn f\u00fcr sich! Lesen sie hier, wie es geht.","breadcrumb":{"@id":"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ionas.com\/wissen\/"},{"@type":"ListItem","position":2,"name":"Vorsorge f\u00fcr den Komplettausfall: Systemabbildsicherung"}]},{"@type":"Article","@id":"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/#article","isPartOf":{"@id":"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/#webpage"},"author":{"@id":"https:\/\/www.ionas.com\/wissen\/#\/schema\/person\/4f6d598597b4cb184645f0851f8bdea7"},"headline":"Vorsorge f\u00fcr den Komplettausfall: Systemabbildsicherung","datePublished":"2015-12-12T18:39:52+00:00","dateModified":"2016-09-10T06:16:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/#webpage"},"wordCount":1009,"commentCount":0,"publisher":{"@id":"https:\/\/www.ionas.com\/wissen\/#organization"},"image":{"@id":"https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ionas.com\/wissen\/wp-content\/uploads\/2015\/12\/Systemabbildung-Dateiversionsverlauf.png","keywords":["datensicherung","image","systemabbild","systemimage","Windows"],"articleSection":["Uncategorized"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ionas.com\/wissen\/vorsorge-fuer-den-komplettausfall-systemabbildsicherung\/#respond"]}]},{"@type":"Person","@id":"https:\/\/www.ionas.com\/wissen\/#\/schema\/person\/4f6d598597b4cb184645f0851f8bdea7","name":"Ralf Dyllick-Brenzinger","sameAs":["http:\/\/www.ionas.com"],"url":"https:\/\/www.ionas.com\/wissen\/author\/rdb\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ionas.com\/wissen\/wp-json\/wp\/v2\/posts\/1995"}],"collection":[{"href":"https:\/\/www.ionas.com\/wissen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ionas.com\/wissen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ionas.com\/wissen\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ionas.com\/wissen\/wp-json\/wp\/v2\/comments?post=1995"}],"version-history":[{"count":38,"href":"https:\/\/www.ionas.com\/wissen\/wp-json\/wp\/v2\/posts\/1995\/revisions"}],"predecessor-version":[{"id":3248,"href":"https:\/\/www.ionas.com\/wissen\/wp-json\/wp\/v2\/posts\/1995\/revisions\/3248"}],"wp:attachment":[{"href":"https:\/\/www.ionas.com\/wissen\/wp-json\/wp\/v2\/media?parent=1995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ionas.com\/wissen\/wp-json\/wp\/v2\/categories?post=1995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ionas.com\/wissen\/wp-json\/wp\/v2\/tags?post=1995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}